{"id":3645,"date":"2024-04-27T12:00:41","date_gmt":"2024-04-27T12:00:41","guid":{"rendered":"https:\/\/learningconnected.com\/?p=3645"},"modified":"2024-05-08T19:01:55","modified_gmt":"2024-05-08T19:01:55","slug":"online-brainstormen-in-7-stappen","status":"publish","type":"post","link":"https:\/\/learningconnected.com\/de\/blog\/online-brainstormen-in-7-stappen\/","title":{"rendered":"Online-Brainstorming in 7 Schritten"},"content":{"rendered":"<p>Willkommen zu unserem dritten Blog \u00fcber Online-Brainstorming. Unser <a href=\"https:\/\/learningconnected.com\/de\/blog\/brainstormen-dat-doen-we-liever-online\/\">erster Blog<\/a> betonte die Bedeutung des Live-Online-Brainstormings, w\u00e4hrend die <a href=\"https:\/\/learningconnected.com\/de\/blog\/een-online-brainstorm-voorbereiden\/\">zweiter Blog<\/a> auf eine optimale Vorbereitung. In diesem neuesten Blog beschreiben wir, wie man ein Online-Brainstorming in 7 Schritten erfolgreich durchf\u00fchrt. Welche das sind, k\u00f6nnen Sie unten lesen!<\/p>\n<h4><strong>1. Beginnen Sie mit einer guten Einleitung<\/strong><\/h4>\n<p>Nat\u00fcrlich beginnen Sie die Sitzung mit einem guten Start: Begr\u00fc\u00dfung, Einchecken (wie sitzen alle?), Vorstellung der Tagesordnung und eine lustige interaktive Einf\u00fchrung, falls sich die Teilnehmer noch nicht kennen.<\/p>\n<h4><strong>2. \u00dcbung mit dem Werkzeug<\/strong><\/h4>\n<p>Nutzen Sie den Chat, das Whiteboard oder ein externes Programm w\u00e4hrend der Brainstorming-Sitzung? Dann f\u00fchren Sie die Teilnehmer zun\u00e4chst mit einer unterhaltsamen, niedrigschwelligen \u00dcbung an diese Programme heran oder machen Sie die Einf\u00fchrung beispielsweise auch mit diesem Tool.<\/p>\n<h4><strong>3. Diskutieren Sie die Bedeutung und die Regeln<\/strong><\/h4>\n<p>Bevor Sie mit dem Brainstorming beginnen, besprechen Sie den Grund f\u00fcr das geplante Brainstorming (warum machen wir das?) und das Hauptziel. Teilen Sie dann die Grundregeln f\u00fcr eine gute Brainstorming-Sitzung mit. Diese sind:<\/p>\n<ul>\n<li>Alle Ideen sind willkommen (je verr\u00fcckter, desto besser!)<\/li>\n<li>Kritisieren Sie nicht<\/li>\n<li>Auf Ideen von anderen aufbauen<\/li>\n<li>Wir setzen auf Quantit\u00e4t<\/li>\n<\/ul>\n<p>Unterst\u00fctzen Sie die ersten drei Schritte visuell mit einpr\u00e4gsamen PowerPoint-Folien.<\/p>\n<h4><strong>4. Beginnen Sie mit einer <em>braindump<\/em><\/strong><\/h4>\n<p>Bevor man mit dem eigentlichen Brainstorming beginnt, ist es sinnvoll, alle vorhandenen Ideen gleich zu sammeln. Dies kann mit einem <em>braindump<\/em>: Jeder Teilnehmer schreibt frei seine Ideen zu dem Thema auf. Das Erfassen aller vorhandenen Ideen, z. B. \u00fcber den Chat, \u00f6ffnet die T\u00fcr f\u00fcr originellere Alternativen.<\/p>\n<h4><strong>5. Umsetzung der gew\u00e4hlten Arbeitsform<\/strong><\/h4>\n<p>Wenn alles gut geht, haben Sie im <a href=\"https:\/\/learningconnected.com\/de\/blog\/een-online-brainstorm-voorbereiden\/\">vorherige Phase<\/a> bereits eine Brainstorming-Variante vorbereitet. Zeit, sie jetzt umzusetzen!<\/p>\n<h4><strong>6. Clustern und Bewerten der gesammelten Ideen<\/strong><\/h4>\n<p>An die Ideenphase schlie\u00dft sich eine Ideenbewertungsphase an, in der die gesammelten Ideen verglichen, bewertet und weiter entwickelt werden. Planen Sie daf\u00fcr 5 bis 10 Minuten nach dem Brainstorming ein, um alle Ideen in logische Themen zu gruppieren.<\/p>\n<p>Eine einfache Methode, um schnell die besten Ideen auszuw\u00e4hlen, besteht darin, die Teilnehmer abstimmen zu lassen. Geben Sie jedem eine Anzahl von Stimmen und lassen Sie sie einzeln und still abstimmen. Lassen Sie sie zum Beispiel die Ideen ankreuzen, die sie am interessantesten finden. Verwenden Sie ein externes Tool wie Mural oder Miro? Oft gibt es die M\u00f6glichkeit, auf Notizen mit einem Daumen oder einem Herz zu antworten. Erstellen Sie nach der Abstimmung eine Liste mit den Ideen, die die meisten Stimmen erhalten haben.<\/p>\n<p>Ein n\u00fctzliches Instrument f\u00fcr die Konvergenz ist die <a href=\"https:\/\/hatrabbits.com\/kies-ideeen-na-het-brainstormen\/\">Bewertungsmatrix<\/a>: ein Modell mit zwei Achsen, die vier Ebenen bilden. Die horizontale Achse bewertet den erforderlichen Aufwand und die vertikale Achse die Auswirkungen. Tragen Sie alle Ideen in die Bewertungsmatrix ein. Ideen mit hoher Wirkung und geringem Aufwand sind ideal: greifen Sie diese zuerst auf. Ideen mit geringer Auswirkung und hohem Aufwand werden besser aufgeschoben.<\/p>\n<h4><strong>7. Diskutieren Sie Folgeschritte<\/strong><\/h4>\n<p>Egal, ob Sie sich sofort entscheiden, welche Ideen Sie aufgreifen wollen oder nicht, nehmen Sie sich am Ende der Sitzung immer Zeit, um die n\u00e4chsten Schritte zu besprechen. Was ist n\u00f6tig, um Ihre Idee umzusetzen? Wer ist f\u00fcr welche Aufgaben zust\u00e4ndig? Und was sind die Fristen? Schicken Sie nach der Sitzung eine Zusammenfassung und die Liste der Aktionspunkte, auf die Sie sich als Gruppe geeinigt haben, an jeden Teilnehmer. Auf diese Weise vermeiden Sie Missverst\u00e4ndnisse und stellen sicher, dass etwas geschieht.<\/p>\n<p>Apropos Action: Wir sind am Ende dieses dritten und zugleich letzten Blogs zum Thema Brainstorming angelangt. Sind Sie bereit f\u00fcr Ihr n\u00e4chstes Live-Online-Brainstorming? Viel Gl\u00fcck!<\/p>","protected":false},"excerpt":{"rendered":"<p>Willkommen zu unserem dritten Blog \u00fcber Online-Brainstorming. In unserem ersten Blog haben wir die Bedeutung von...<\/p>","protected":false},"author":25,"featured_media":3648,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3645","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geen-categorie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Online brainstormen in 7 stappen - Learning Connected<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/learningconnected.com\/de\/blog\/online-brainstormen-in-7-stappen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Online brainstormen in 7 stappen - Learning Connected\" \/>\n<meta property=\"og:description\" content=\"Welkom bij onze derde blog over online brainstormen. Onze eerste blog benadrukte het belang van...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/learningconnected.com\/de\/blog\/online-brainstormen-in-7-stappen\/\" \/>\n<meta property=\"og:site_name\" content=\"Learning Connected\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-27T12:00:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-08T19:01:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/learningconnected.com\/wp-content\/uploads\/2024\/04\/pexels-cottonbro-6321244-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Linda de Wit\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Linda de Wit\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/learningconnected.com\\\/blog\\\/online-brainstormen-in-7-stappen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/learningconnected.com\\\/blog\\\/online-brainstormen-in-7-stappen\\\/\"},\"author\":{\"name\":\"Linda de Wit\",\"@id\":\"https:\\\/\\\/learningconnected.com\\\/#\\\/schema\\\/person\\\/36ddcec6b34a7123473317892c2d56e6\"},\"headline\":\"Online brainstormen in 7 stappen\",\"datePublished\":\"2024-04-27T12:00:41+00:00\",\"dateModified\":\"2024-05-08T19:01:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/learningconnected.com\\\/blog\\\/online-brainstormen-in-7-stappen\\\/\"},\"wordCount\":622,\"image\":{\"@id\":\"https:\\\/\\\/learningconnected.com\\\/blog\\\/online-brainstormen-in-7-stappen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/learningconnected.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/pexels-cottonbro-6321244-scaled.jpg\",\"articleSection\":[\"Geen categorie\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/learningconnected.com\\\/blog\\\/online-brainstormen-in-7-stappen\\\/\",\"url\":\"https:\\\/\\\/learningconnected.com\\\/blog\\\/online-brainstormen-in-7-stappen\\\/\",\"name\":\"Online brainstormen in 7 stappen - Learning Connected\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/learningconnected.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/learningconnected.com\\\/blog\\\/online-brainstormen-in-7-stappen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/learningconnected.com\\\/blog\\\/online-brainstormen-in-7-stappen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/learningconnected.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/pexels-cottonbro-6321244-scaled.jpg\",\"datePublished\":\"2024-04-27T12:00:41+00:00\",\"dateModified\":\"2024-05-08T19:01:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/learningconnected.com\\\/#\\\/schema\\\/person\\\/36ddcec6b34a7123473317892c2d56e6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/learningconnected.com\\\/blog\\\/online-brainstormen-in-7-stappen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/learningconnected.com\\\/blog\\\/online-brainstormen-in-7-stappen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/learningconnected.com\\\/blog\\\/online-brainstormen-in-7-stappen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/learningconnected.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/pexels-cottonbro-6321244-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/learningconnected.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/pexels-cottonbro-6321244-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/learningconnected.com\\\/blog\\\/online-brainstormen-in-7-stappen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/learningconnected.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Online brainstormen in 7 stappen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/learningconnected.com\\\/#website\",\"url\":\"https:\\\/\\\/learningconnected.com\\\/\",\"name\":\"Learning Connected\",\"description\":\"Wij helpen jou om effectief live online te communiceren\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/learningconnected.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/learningconnected.com\\\/#\\\/schema\\\/person\\\/36ddcec6b34a7123473317892c2d56e6\",\"name\":\"Linda de Wit\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc6268e1c90be2ca47113a01420f9a75966726c2b06685fc950a663e773885eb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc6268e1c90be2ca47113a01420f9a75966726c2b06685fc950a663e773885eb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc6268e1c90be2ca47113a01420f9a75966726c2b06685fc950a663e773885eb?s=96&d=mm&r=g\",\"caption\":\"Linda de Wit\"},\"url\":\"https:\\\/\\\/learningconnected.com\\\/de\\\/blog\\\/author\\\/lindadewit\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Online-Brainstorming in 7 Schritten - Learning Connected","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/learningconnected.com\/de\/blog\/online-brainstormen-in-7-stappen\/","og_locale":"de_DE","og_type":"article","og_title":"Online brainstormen in 7 stappen - Learning Connected","og_description":"Welkom bij onze derde blog over online brainstormen. Onze eerste blog benadrukte het belang van...","og_url":"https:\/\/learningconnected.com\/de\/blog\/online-brainstormen-in-7-stappen\/","og_site_name":"Learning Connected","article_published_time":"2024-04-27T12:00:41+00:00","article_modified_time":"2024-05-08T19:01:55+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/learningconnected.com\/wp-content\/uploads\/2024\/04\/pexels-cottonbro-6321244-scaled.jpg","type":"image\/jpeg"}],"author":"Linda de Wit","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"Linda de Wit","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/learningconnected.com\/blog\/online-brainstormen-in-7-stappen\/#article","isPartOf":{"@id":"https:\/\/learningconnected.com\/blog\/online-brainstormen-in-7-stappen\/"},"author":{"name":"Linda de Wit","@id":"https:\/\/learningconnected.com\/#\/schema\/person\/36ddcec6b34a7123473317892c2d56e6"},"headline":"Online brainstormen in 7 stappen","datePublished":"2024-04-27T12:00:41+00:00","dateModified":"2024-05-08T19:01:55+00:00","mainEntityOfPage":{"@id":"https:\/\/learningconnected.com\/blog\/online-brainstormen-in-7-stappen\/"},"wordCount":622,"image":{"@id":"https:\/\/learningconnected.com\/blog\/online-brainstormen-in-7-stappen\/#primaryimage"},"thumbnailUrl":"https:\/\/learningconnected.com\/wp-content\/uploads\/2024\/04\/pexels-cottonbro-6321244-scaled.jpg","articleSection":["Geen categorie"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/learningconnected.com\/blog\/online-brainstormen-in-7-stappen\/","url":"https:\/\/learningconnected.com\/blog\/online-brainstormen-in-7-stappen\/","name":"Online-Brainstorming in 7 Schritten - Learning Connected","isPartOf":{"@id":"https:\/\/learningconnected.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/learningconnected.com\/blog\/online-brainstormen-in-7-stappen\/#primaryimage"},"image":{"@id":"https:\/\/learningconnected.com\/blog\/online-brainstormen-in-7-stappen\/#primaryimage"},"thumbnailUrl":"https:\/\/learningconnected.com\/wp-content\/uploads\/2024\/04\/pexels-cottonbro-6321244-scaled.jpg","datePublished":"2024-04-27T12:00:41+00:00","dateModified":"2024-05-08T19:01:55+00:00","author":{"@id":"https:\/\/learningconnected.com\/#\/schema\/person\/36ddcec6b34a7123473317892c2d56e6"},"breadcrumb":{"@id":"https:\/\/learningconnected.com\/blog\/online-brainstormen-in-7-stappen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/learningconnected.com\/blog\/online-brainstormen-in-7-stappen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/learningconnected.com\/blog\/online-brainstormen-in-7-stappen\/#primaryimage","url":"https:\/\/learningconnected.com\/wp-content\/uploads\/2024\/04\/pexels-cottonbro-6321244-scaled.jpg","contentUrl":"https:\/\/learningconnected.com\/wp-content\/uploads\/2024\/04\/pexels-cottonbro-6321244-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/learningconnected.com\/blog\/online-brainstormen-in-7-stappen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/learningconnected.com\/"},{"@type":"ListItem","position":2,"name":"Online brainstormen in 7 stappen"}]},{"@type":"WebSite","@id":"https:\/\/learningconnected.com\/#website","url":"https:\/\/learningconnected.com\/","name":"Learning Connected","description":"Wir helfen Ihnen bei der effektiven Live-Online-Kommunikation","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/learningconnected.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/learningconnected.com\/#\/schema\/person\/36ddcec6b34a7123473317892c2d56e6","name":"Linda de Wit","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/dc6268e1c90be2ca47113a01420f9a75966726c2b06685fc950a663e773885eb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dc6268e1c90be2ca47113a01420f9a75966726c2b06685fc950a663e773885eb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dc6268e1c90be2ca47113a01420f9a75966726c2b06685fc950a663e773885eb?s=96&d=mm&r=g","caption":"Linda de Wit"},"url":"https:\/\/learningconnected.com\/de\/blog\/author\/lindadewit\/"}]}},"_links":{"self":[{"href":"https:\/\/learningconnected.com\/de\/wp-json\/wp\/v2\/posts\/3645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/learningconnected.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/learningconnected.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/learningconnected.com\/de\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/learningconnected.com\/de\/wp-json\/wp\/v2\/comments?post=3645"}],"version-history":[{"count":3,"href":"https:\/\/learningconnected.com\/de\/wp-json\/wp\/v2\/posts\/3645\/revisions"}],"predecessor-version":[{"id":3652,"href":"https:\/\/learningconnected.com\/de\/wp-json\/wp\/v2\/posts\/3645\/revisions\/3652"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/learningconnected.com\/de\/wp-json\/wp\/v2\/media\/3648"}],"wp:attachment":[{"href":"https:\/\/learningconnected.com\/de\/wp-json\/wp\/v2\/media?parent=3645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/learningconnected.com\/de\/wp-json\/wp\/v2\/categories?post=3645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/learningconnected.com\/de\/wp-json\/wp\/v2\/tags?post=3645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}